{"id":1899,"date":"2022-06-08T11:56:15","date_gmt":"2022-06-08T09:56:15","guid":{"rendered":"https:\/\/academia-musica.at\/musikschule\/?page_id=1899"},"modified":"2025-10-22T13:16:26","modified_gmt":"2025-10-22T11:16:26","slug":"gesang","status":"publish","type":"page","link":"https:\/\/academia-musica.at\/musikschule\/unterricht\/gesang\/","title":{"rendered":"Gesang"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Header&#8220; _builder_version=&#8220;4.16.0&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(31,31,38,0.88) 0%|rgba(31,31,38,0.24) 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_color_gradient_start=&#8220;rgba(31,31,38,0.88)&#8220; background_color_gradient_end=&#8220;rgba(31,31,38,0.24)&#8220; background_image=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2022\/06\/music-1363069_1920.jpg&#8220; custom_margin=&#8220;-12vw||||false|false&#8220; custom_padding=&#8220;10vw||0px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.18.0&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(67,78,92,0.32) 0%|rgba(31,31,38,0.71) 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_color_gradient_start=&#8220;rgba(67,78,92,0.32)&#8220; background_color_gradient_end=&#8220;rgba(31,31,38,0.71)&#8220; background_image=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2022\/06\/music-2200032_1920.jpg&#8220; background_position=&#8220;top_center&#8220; width=&#8220;90%&#8220; max_width=&#8220;none&#8220; module_alignment=&#8220;left&#8220; custom_margin=&#8220;-8vw||||false|false&#8220; custom_margin_tablet=&#8220;|auto||0px|false|false&#8220; custom_margin_last_edited=&#8220;off|desktop&#8220; custom_padding=&#8220;18vw|20px|18vw|20px|false|true&#8220; custom_padding_tablet=&#8220;24vw||24vw||true|false&#8220; custom_padding_phone=&#8220;31vw||||false|false&#8220; border_color_all=&#8220;#1f1f26&#8243; border_width_right=&#8220;8vw&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.17.3&#8243; text_font=&#8220;Lato||||||||&#8220; text_font_size=&#8220;20px&#8220; header_font=&#8220;Prata||||||||&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;85px&#8220; header_line_height=&#8220;1.2em&#8220; header_4_font=&#8220;Lato|||on|||||&#8220; header_4_text_color=&#8220;#bfbfbf&#8220; header_4_font_size=&#8220;20px&#8220; header_4_line_height=&#8220;1.5em&#8220; background_layout=&#8220;dark&#8220; custom_padding=&#8220;|15vw||20vw|false|false&#8220; custom_padding_tablet=&#8220;|||10vw|false|false&#8220; custom_padding_phone=&#8220;|||10vw|false|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; text_font_size_tablet=&#8220;20px&#8220; text_font_size_phone=&#8220;20px&#8220; text_font_size_last_edited=&#8220;on|desktop&#8220; header_font_size_tablet=&#8220;60px&#8220; header_font_size_phone=&#8220;35px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_4_font_size_tablet=&#8220;20px&#8220; header_4_font_size_phone=&#8220;16px&#8220; header_4_font_size_last_edited=&#8220;on|tablet&#8220; header_4_text_shadow_style=&#8220;preset1&#8243; header_4_text_shadow_horizontal_length=&#8220;0.1em&#8220; header_4_text_shadow_blur_strength=&#8220;0em&#8220; global_colors_info=&#8220;{}&#8220; header_4_text_shadow_horizontal_length__hover_enabled=&#8220;off|desktop&#8220;]<\/p>\n<h1>Gesang<\/h1>\n<h4 style=\"text-align: left\">Solo | Chor<\/h4>\n<h4 style=\"text-align: left\"><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; make_equal=&#8220;on&#8220; module_class=&#8220;dh-valign-center-row&#8220; _builder_version=&#8220;4.17.4&#8243; positioning=&#8220;absolute&#8220; position_origin_a=&#8220;bottom_left&#8220; position_origin_a_tablet=&#8220;&#8220; position_origin_a_phone=&#8220;&#8220; position_origin_a_last_edited=&#8220;on|desktop&#8220; position_origin_f_tablet=&#8220;&#8220; position_origin_f_phone=&#8220;&#8220; position_origin_f_last_edited=&#8220;on|desktop&#8220; position_origin_r_tablet=&#8220;&#8220; position_origin_r_phone=&#8220;&#8220; position_origin_r_last_edited=&#8220;on|desktop&#8220; width=&#8220;90%&#8220; max_width=&#8220;none&#8220; custom_margin=&#8220;|auto||0px|false|false&#8220; custom_padding=&#8220;0px||0px|10vw|true|false&#8220; positioning_tablet=&#8220;none&#8220; positioning_phone=&#8220;&#8220; positioning_last_edited=&#8220;on|tablet&#8220; border_radii=&#8220;off|||50px|&#8220; box_shadow_style=&#8220;preset4&#8243; box_shadow_horizontal=&#8220;30vw&#8220; box_shadow_vertical=&#8220;0px&#8220; box_shadow_color=&#8220;#ffffff&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#x33;||divi||400&#8243; icon_color=&#8220;#FFFFFF&#8220; icon_width=&#8220;74px&#8220; url=&#8220;#inhalt&#8220; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220;][\/et_pb_icon][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.17.4&#8243; background_color=&#8220;rgba(131,0,233,0.5)&#8220; custom_padding=&#8220;60px|4%|60px|4%|true|true&#8220; border_radii=&#8220;off|50px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.17.3&#8243; header_3_font=&#8220;Prata||||||||&#8220; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.3em&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;||4px||false|false&#8220; header_3_font_size_tablet=&#8220;22px&#8220; header_3_font_size_phone=&#8220;20px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Sie interessieren sich f\u00fcr dieses Instrument?<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwMTYiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; button_text=&#8220;Jetzt Anmelden&#8220; _builder_version=&#8220;4.18.0&#8243; _dynamic_attributes=&#8220;button_url&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;12px&#8220; button_bg_color=&#8220;rgba(0,0,0,0)&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;2.6px&#8220; button_font=&#8220;|700||on|||||&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;|||0px|false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;About&#8220; module_id=&#8220;inhalt&#8220; _builder_version=&#8220;4.17.3&#8243; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2022\/06\/Gesang_2.jpg&#8220; _builder_version=&#8220;4.18.0&#8243; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover=&#8220;105%|105%&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.17.3&#8243; header_font=&#8220;Prata||||||||&#8220; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;Lato|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Gesang<\/h4>\n<h2>\u00a0<span class=\"fontstyle0\">Melodische T\u00f6ne der Seele<\/span> <\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.18.0&#8243; text_line_height=&#8220;2em&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span class=\"fontstyle0\">Gesang ist die Kunst des Singens. Es bezieht sich auf die menschliche Stimme und die F\u00e4higkeit, musikalische T\u00f6ne und Worte auszudr\u00fccken. Beim Gesang geht es darum, eine Melodie oder ein Lied zu interpretieren und die Stimme entsprechend zu modulieren, um Emotionen, Bedeutungen und Ausdrucksformen zu vermiteln. Gesang kann solo oder in einer Gruppe ausgef\u00fchrt werden und ist ein wichtiger Bestandteil von Musikgenres wie Pop, Rock, Klassik, Jazz, Blues und vielen anderen. Der Gesang kann auch als therapeutisches Mitel eingesetzt werden, um die Atmung, die Stimme und die allgemeine Gesundheit zu verbessern.<\/span><\/p>\n<p>\u00a0<span class=\"fontstyle0\">Im Gesangsunterricht lernt man verschiedene Gesangstechniken, die darauf abzielen, die Stimme zu trainieren, zu verbessern und zu sch\u00fctzen. Dazu geh\u00f6ren Atem- und Stimm\u00fcbungen, Artikulation, Phrasierung und Tonbildung. Der Gesangslehrer kann auch dabei helfen, die richtige Haltung und Atmung zu entwickeln, um eine optimale Klangqualit\u00e4t und -projektion zu erreichen. Au\u00dferdem kann im Gesangsunterricht auch an der Interpretation von Liedern gearbeitet werden, um eine emotionale Verbindung zum Publikum aufzubauen und eine \u00fcberzeugende Performance zu liefern.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Details&#8220; _builder_version=&#8220;4.16&#8243; da_disable_devices=&#8220;off|off|off&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.17.4&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Lehrer<\/h4>\n<h2>Unser Team<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2024\/11\/Defne-Aydin.jpg&#8220; title_text=&#8220;Defne Aydin&#8220; align=&#8220;center&#8220; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; width=&#8220;70%&#8220; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center\">Gesang<\/h4>\n<h3 style=\"text-align: center\">Defne Aydin<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2024\/11\/Arango-Velasquez-2.jpg&#8220; title_text=&#8220;Arango Vel\u00e1squez 2&#8243; align=&#8220;center&#8220; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; width=&#8220;71%&#8220; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.25.1&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center\">Gesang<\/h4>\n<h3 style=\"text-align: center\">Tom\u00e1s Arango Vel\u00e1squez<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2025\/10\/Burcu-Kurt.jpg&#8220; title_text=&#8220;Burcu Kurt&#8220; align=&#8220;center&#8220; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; width=&#8220;71%&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.25.1&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; hover_enabled=&#8220;0&#8243; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243; header_3_text_align=&#8220;center&#8220; header_4_text_align=&#8220;center&#8220; text_orientation=&#8220;center&#8220;]<\/p>\n<h4 style=\"text-align: center\">Operngesang-Sprechgesang- Unterhaltungsmusik<\/h4>\n<h4 style=\"text-align: center\">Gesang<\/h4>\n<h3 style=\"text-align: center\">Burcu Kurt<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Details&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;||29px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.18.0&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Jetzt Anmelden<\/h4>\n<h2>Unser Angebot<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; text_line_height=&#8220;2em&#8220; max_width=&#8220;636px&#8220; max_width_tablet=&#8220;636px&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_margin=&#8220;|-385px||||&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>Was passiert im Unterricht?<\/strong><\/p>\n<p><span class=\"fontstyle0\">Im Gesangsunterricht hat der Lehrer verschiedene Aufgaben und Ziele, die er\/sie mit dem Sch\u00fcler erreichen m\u00f6chte. Einige Beispiele daf\u00fcr sind:<\/span><\/p>\n<p><span class=\"fontstyle0\"><strong>Stimmbildung:<\/strong> Der Lehrer hilft dem Sch\u00fcler, seine Stimme besser zu kontrollieren, indem er Techniken zur Atmung, Artikulation, Intonation und Resonanz lehrt.<\/span><\/p>\n<p><span class=\"fontstyle0\"><strong>Repertoireauswahl:<\/strong> Der Lehrer arbeitet mit dem Sch\u00fcler daran, passende Lieder oder St\u00fccke auszuw\u00e4hlen, die seinem Niveau und seinen Interessen entsprechen.<\/span><\/p>\n<p><span class=\"fontstyle0\"><strong>Interpretation:<\/strong> Der Lehrer unterst\u00fctzt den Sch\u00fcler dabei, die Bedeutung und Emotionen eines Liedes oder St\u00fccks zu verstehen und diese in seiner Performance auszudr\u00fccken.<\/span><\/p>\n<p><span class=\"fontstyle0\"><strong>Performance-F\u00e4higkeiten:<\/strong> Der Lehrer arbeitet mit dem Sch\u00fcler an verschiedenen F\u00e4higkeiten, die bei einer \u00f6ffentlichen Auff\u00fchrung wichtig sind, wie z.B. Mikrofontechnik, B\u00fchnenpr\u00e4senz und Umgang mit Lampenfieber.<\/span><\/p>\n<p><span class=\"fontstyle0\"><strong>Musiktheorie:<\/strong> Der Lehrer kann auch Musiktheorie-Unterricht geben, um dem Sch\u00fcler ein besseres Verst\u00e4ndnis von Musikstrukturen, Akkorden, Tonleitern und Notation zu vermiteln, was ihm beim Singen und Komponieren helfen kann.<\/span><\/p>\n<p><span class=\"fontstyle0\"><\/span><\/p>\n<p><span class=\"fontstyle0\">Insgesamt geht es im Gesangsunterricht darum, die F\u00e4higkeiten des Sch\u00fclers zu verbessern, seine Technik zu verfeinern und ihm die Werkzeuge und das Wissen zu geben, die er ben\u00f6tigt, um als S\u00e4nger zu wachsen und erfolgreich zu sein.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Schwerpunkt<\/h4>\n<h2>Unterrichtsthemen<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Verbesserung von Intonation, Artikulation und Ausdruckskraft&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Entwicklung von Atemtechnik und Stimmumfang&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Interpretation von Songtexten und Einbindung in Performance&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Vorbereitung auf Studio- und Live-Auftritte sowie Gesangswettbewerbe&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Entdeckung und Entwicklung des eigenen Stils und Klangs&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Gesundes Singen: Stimmhygiene und Vermeidung von Verletzungen&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Arbeit an K\u00f6rperhaltung und B\u00fchnenpr\u00e4senz f\u00fcr selbstbewusste Auftritte&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Improvisation und Songwriting f\u00fcr kreativen Ausdruck und Musikkomposition&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Geh\u00f6rbildung und Harmonielehre f\u00fcr besseres Verst\u00e4ndnis von Musik und Gesang&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;1px||0px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||50px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;https:\/\/academia-musica.at\/musikschule\/kontakt\/&#8220; button_text=&#8220;Jetzt anmelden&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;18px&#8220; button_text_color=&#8220;#000000&#8243; button_bg_color=&#8220;RGBA(255,255,255,0)&#8220; button_border_color=&#8220;#bea88f&#8220; button_letter_spacing=&#8220;2px&#8220; button_font=&#8220;Prata|500|||||||&#8220; custom_padding=&#8220;15px|35px|15px|35px|true|true&#8220; animation_style=&#8220;flip&#8220; box_shadow_style=&#8220;preset3&#8243; box_shadow_vertical=&#8220;14px&#8220; box_shadow_blur=&#8220;10px&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#d4af37&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_text_color__hover_enabled=&#8220;on|hover&#8220; button_text_color__hover=&#8220;#FFFFFF&#8220; custom_margin__hover_enabled=&#8220;off|desktop&#8220; custom_padding__hover_enabled=&#8220;on|hover&#8220; custom_padding__hover=&#8220;|50px||50px|true|true&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gesang Solo | Chor Sie interessieren sich f\u00fcr dieses Instrument?Gesang \u00a0Melodische T\u00f6ne der Seele Gesang ist die Kunst des Singens. Es bezieht sich auf die menschliche Stimme und die F\u00e4higkeit, musikalische T\u00f6ne und Worte auszudr\u00fccken. Beim Gesang geht es darum, eine Melodie oder ein Lied zu interpretieren und die Stimme entsprechend zu modulieren, um Emotionen, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1872,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1899"}],"collection":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/comments?post=1899"}],"version-history":[{"count":4,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1899\/revisions"}],"predecessor-version":[{"id":2595,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1899\/revisions\/2595"}],"up":[{"embeddable":true,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1872"}],"wp:attachment":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/media?parent=1899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}