{"id":1904,"date":"2022-06-08T11:59:11","date_gmt":"2022-06-08T09:59:11","guid":{"rendered":"https:\/\/academia-musica.at\/musikschule\/?page_id=1904"},"modified":"2024-11-30T16:12:51","modified_gmt":"2024-11-30T15:12:51","slug":"klavier","status":"publish","type":"page","link":"https:\/\/academia-musica.at\/musikschule\/unterricht\/klavier\/","title":{"rendered":"Klavier"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Header&#8220; _builder_version=&#8220;4.17.4&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(31,31,38,0.88) 0%|rgba(31,31,38,0.24) 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_color_gradient_start=&#8220;rgba(31,31,38,0.88)&#8220; background_color_gradient_end=&#8220;rgba(31,31,38,0.24)&#8220; background_image=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2022\/06\/music-1363069_1920.jpg&#8220; custom_margin=&#8220;-12vw||||false|false&#8220; custom_margin_tablet=&#8220;-10vw||||false|false&#8220; custom_margin_phone=&#8220;-10vw||||false|false&#8220; custom_margin_last_edited=&#8220;off|desktop&#8220; custom_padding=&#8220;10vw||0px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.17.4&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;rgba(67,78,92,0.32) 0%|rgba(31,31,38,0.71) 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_color_gradient_start=&#8220;rgba(67,78,92,0.32)&#8220; background_color_gradient_end=&#8220;rgba(31,31,38,0.71)&#8220; background_image=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2021\/07\/header_bg.jpg&#8220; background_position=&#8220;top_center&#8220; width=&#8220;90%&#8220; max_width=&#8220;none&#8220; module_alignment=&#8220;left&#8220; custom_margin=&#8220;-8vw||||false|false&#8220; custom_margin_tablet=&#8220;|auto||0px|false|false&#8220; custom_margin_last_edited=&#8220;off|desktop&#8220; custom_padding=&#8220;18vw|20px|18vw|20px|false|true&#8220; custom_padding_tablet=&#8220;24vw||24vw||true|false&#8220; custom_padding_phone=&#8220;31vw||||false|false&#8220; border_color_all=&#8220;#1f1f26&#8243; border_width_right=&#8220;8vw&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; text_font=&#8220;Lato||||||||&#8220; text_font_size=&#8220;20px&#8220; header_font=&#8220;Prata||||||||&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;85px&#8220; header_line_height=&#8220;1.2em&#8220; header_4_font=&#8220;Lato|||on|||||&#8220; header_4_text_color=&#8220;#bfbfbf&#8220; header_4_font_size=&#8220;20px&#8220; header_4_line_height=&#8220;1.5em&#8220; background_layout=&#8220;dark&#8220; custom_padding=&#8220;|15vw||20vw|false|false&#8220; custom_padding_tablet=&#8220;|||10vw|false|false&#8220; custom_padding_phone=&#8220;|||10vw|false|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; text_font_size_tablet=&#8220;20px&#8220; text_font_size_phone=&#8220;20px&#8220; text_font_size_last_edited=&#8220;on|desktop&#8220; header_font_size_tablet=&#8220;60px&#8220; header_font_size_phone=&#8220;35px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_4_font_size_tablet=&#8220;20px&#8220; header_4_font_size_phone=&#8220;16px&#8220; header_4_font_size_last_edited=&#8220;on|tablet&#8220; header_4_text_shadow_style=&#8220;preset1&#8243; header_4_text_shadow_horizontal_length=&#8220;0.1em&#8220; header_4_text_shadow_blur_strength=&#8220;0em&#8220; global_colors_info=&#8220;{}&#8220; header_4_text_shadow_horizontal_length__hover_enabled=&#8220;off|desktop&#8220;]<\/p>\n<h1>Klavier<\/h1>\n<h4 style=\"text-align: left\"><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; make_equal=&#8220;on&#8220; module_class=&#8220;dh-valign-center-row&#8220; _builder_version=&#8220;4.17.4&#8243; positioning=&#8220;absolute&#8220; position_origin_a=&#8220;bottom_left&#8220; position_origin_a_tablet=&#8220;&#8220; position_origin_a_phone=&#8220;&#8220; position_origin_a_last_edited=&#8220;on|desktop&#8220; position_origin_f_tablet=&#8220;&#8220; position_origin_f_phone=&#8220;&#8220; position_origin_f_last_edited=&#8220;on|desktop&#8220; position_origin_r_tablet=&#8220;&#8220; position_origin_r_phone=&#8220;&#8220; position_origin_r_last_edited=&#8220;on|desktop&#8220; width=&#8220;90%&#8220; max_width=&#8220;none&#8220; custom_margin=&#8220;|auto||0px|false|false&#8220; custom_padding=&#8220;0px||0px|10vw|true|false&#8220; positioning_tablet=&#8220;none&#8220; positioning_phone=&#8220;&#8220; positioning_last_edited=&#8220;on|tablet&#8220; border_radii=&#8220;off|||50px|&#8220; box_shadow_style=&#8220;preset4&#8243; box_shadow_horizontal=&#8220;30vw&#8220; box_shadow_vertical=&#8220;0px&#8220; box_shadow_color=&#8220;#ffffff&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#x33;||divi||400&#8243; icon_color=&#8220;#FFFFFF&#8220; icon_width=&#8220;74px&#8220; url=&#8220;#inhalt&#8220; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; animation_style=&#8220;slide&#8220; animation_direction=&#8220;top&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220;][\/et_pb_icon][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.17.4&#8243; background_color=&#8220;rgba(131,0,233,0.5)&#8220; custom_padding=&#8220;60px|4%|60px|4%|true|true&#8220; border_radii=&#8220;off|50px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.17.3&#8243; header_3_font=&#8220;Prata||||||||&#8220; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.3em&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;||4px||false|false&#8220; header_3_font_size_tablet=&#8220;22px&#8220; header_3_font_size_phone=&#8220;20px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Sie interessieren sich f\u00fcr dieses Instrument?<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwMTYiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@&#8220; button_text=&#8220;Jetzt Anmelden&#8220; _builder_version=&#8220;4.18.0&#8243; _dynamic_attributes=&#8220;button_url&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;12px&#8220; button_bg_color=&#8220;rgba(0,0,0,0)&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;2.6px&#8220; button_font=&#8220;|700||on|||||&#8220; background_layout=&#8220;dark&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;|||0px|false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;About&#8220; module_id=&#8220;inhalt&#8220; _builder_version=&#8220;4.17.3&#8243; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2022\/06\/Klavier.jpg&#8220; _builder_version=&#8220;4.18.0&#8243; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Klavier<\/h4>\n<h2><span class=\"fontstyle0\">Ein Instrument f\u00fcr die Seele<\/span> <\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.18.0&#8243; text_line_height=&#8220;2em&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span class=\"fontstyle0\">Das Klavier ist ein Tasteninstrument, das aus einer Reihe von horizontal angeordneten Tasten besteht, die mit H\u00e4mmerchen verbunden sind, welche wiederum die Saiten im Inneren des Klaviers anschlagen. Jede Taste entspricht einer bestimmten Tonh\u00f6he und Dynamik, die der Spieler durch die St\u00e4rke des Anschlags variieren kann. Das Klavier ist ein sehr vielseitiges Instrument, das in vielen verschiedenen Musikgenres und Stilrichtungen eingesetzt wird, von klassischer Musik \u00fcber Pop und Rock bis hin zu Jazz und Blues. Es ist auch ein beliebtes Instrument f\u00fcr Solo- und Kammermusik sowie als Begleitinstrument.<\/span><\/p>\n<p><span class=\"fontstyle0\">Das Klavier ist ein sehr vielseitiges Instrument und wird in vielen Musikrichtungen eingesetzt. Es gibt unterschiedliche Arten von Klavieren, zum Beispiel das Fl\u00fcgelklavier und das Upright Piano oder auch das E-Piano. Das Fl\u00fcgelklavier zeichnet sich durch seinen charakteristischen Klang aus, der sehr volumin\u00f6s und klangvoll ist. Es wird oft in Konzerten oder Aufnahmen verwendet. Das Upright Piano ist ein vertikales Klavier und hat aufgrund seiner Bauweise einen etwas anderen Klang als das Fl\u00fcgelklavier. Es ist in der Regel kompakter und eignet sich gut f\u00fcr den Einsatz in kleineren R\u00e4umen.<\/span><\/p>\n<p><span class=\"fontstyle0\">Das Klavier hat einen sehr breiten Dynamikbereich, was bedeutet, dass es sowohl sehr leise als auch sehr laut gespielt werden kann. Das erm\u00f6glicht es dem Spieler, eine Vielzahl von Ausdrucksm\u00f6glichkeiten zu nutzen und verschiedene Stimmungen und Atmosph\u00e4ren zu erzeugen. Klaviermusik kann sehr komplex sein und erfordert viel \u00dcbung und K\u00f6nnen, um sie zu spielen. Im Klavierunterricht lernt man die Grundlagen des Klavierspiels wie Notenlesen, Rhythmus und Technik. Man lernt auch, wie man verschiedene Musikstile und &#8211; genres spielt und wie man seine eigene musikalische Stimme findet.<\/span><\/p>\n<p><span class=\"fontstyle0\">Das Klavier ist auch ein beliebtes Instrument f\u00fcr die Begleitung von Gesang oder anderen Instrumenten, da es in der Lage ist, eine breite Palete von Kl\u00e4ngen und Stilen zu erzeugen. Es ist auch ein h\u00e4ufig verwendetes Instrument in der Komposition von Musik, da es es dem Komponisten erm\u00f6glicht, schnell und einfach verschiedene musikalische Ideen auszuprobieren und zu erforschen.<\/span><\/p>\n<p><span class=\"fontstyle0\">Insgesamt ist das Klavier ein wunderbares Instrument, das eine wichtige Rolle in der Musikgeschichte spielt und viele Musiker und Zuh\u00f6rer auf der ganzen Welt begeistert.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Details&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;||0px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.17.4&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Lehrer<\/h4>\n<h2>Unser Team<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2023\/04\/Hafez-Babashahi.jpg&#8220; title_text=&#8220;Hafez Babashahi&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center\">Klavier<\/h4>\n<h3 style=\"text-align: center\">Hafez Babashahi<\/h3>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2023\/04\/Giuseppe-Terza.jpg&#8220; title_text=&#8220;Giuseppe-Terza&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center\">Klavier<\/h4>\n<h3 style=\"text-align: center\">Giuseppe Terza<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2023\/04\/Pang-Chen-1.jpg&#8220; title_text=&#8220;Pang Chen&#8220; align=&#8220;center&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; module_alignment=&#8220;left&#8220; min_height=&#8220;100px&#8220; height=&#8220;253px&#8220; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4 style=\"text-align: center\">Klavier<\/h4>\n<h3 style=\"text-align: center\">Pang Chen<\/h3>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/academia-musica.at\/musikschule\/wp-content\/uploads\/sites\/2\/2024\/11\/Arango-Velasquez-1.jpg&#8220; title_text=&#8220;Arango Vel\u00e1squez 1&#8243; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|50px||50px|&#8220; box_shadow_style=&#8220;preset2&#8243; box_shadow_horizontal=&#8220;9px&#8220; box_shadow_vertical=&#8220;9px&#8220; box_shadow_color=&#8220;#5a5a5a&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243; align=&#8220;center&#8220; width=&#8220;52%&#8220;][\/et_pb_image][et_pb_text _builder_version=&#8220;4.25.1&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; hover_enabled=&#8220;0&#8243; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4 style=\"text-align: center\">Klavier<\/h4>\n<h3 style=\"text-align: center\">Tom\u00e1s Arango Vel\u00e1squez<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Details&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;36px||33px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.18.0&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Jetzt Anmelden<\/h4>\n<h2>Unser Angebot<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; text_line_height=&#8220;2em&#8220; max_width=&#8220;636px&#8220; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;100%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_margin=&#8220;|-385px||||&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>Was passiert im Unterricht?<\/strong><\/p>\n<p><span class=\"fontstyle0\">Im Klavierunterricht lernt man zun\u00e4chst die Grundlagen des Klavierspielens, wie zum Beispiel das Lesen von Noten, Rhythmen und Finger\u00fcbungen. Man lernt auch die richtige Hand- und Fingerhaltung, um eine gute Technik zu entwickeln und Verletzungen zu vermeiden.<\/span><\/p>\n<p><span class=\"fontstyle0\">Sobald man diese Grundlagen beherrscht, beginnt man mit dem Erlernen von St\u00fccken. Dabei geht es nicht nur um das blo\u00dfe Spielen der Noten, sondern auch um die Interpretation des St\u00fccks und die Entwicklung eines eigenen Stils. Der Lehrer hilft einem dabei, die Musik richtig zu interpretieren und den Ausdruck und die Emotionen in der Musik zum Ausdruck zu bringen.<\/span><\/p>\n<p><span class=\"fontstyle0\">Im Klavierunterricht werden oft verschiedene Stile und Genres von Musik behandelt, von klassischer Musik bis hin zu Jazz, Blues und Pop. Man lernt, wie man diese verschiedenen Stile spielt und wie man seinen eigenen musikalischen Ausdruck in jedem Stil findet.<\/span><\/p>\n<p><span class=\"fontstyle0\">Ein weiterer wichtiger Aspekt des Klavierunterrichts ist das \u00dcben. Der Lehrer gibt \u00dcbungsaufgaben und hilft einem, eine effektive \u00dcbe-Routine zu entwickeln, um schnelle Fortschrite zu machen. Man lernt auch, wie man sich auf Konzerte oder Auff\u00fchrungen vorbereitet und wie man mit Nervosit\u00e4t und Lampenfieber umgeht.<\/span><\/p>\n<p><span class=\"fontstyle0\">Zusammenfassend kann man sagen, dass man im Klavierunterricht nicht nur das Klavierspielen lernt, sondern auch wichtige F\u00e4higkeiten wie Disziplin, Durchhalteverm\u00f6gen und kreatives Denken entwickelt. Es ist eine lohnende und erf\u00fcllende Erfahrung, die einem ein Leben lang Freude bereiten kann.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.18.0&#8243; header_2_font=&#8220;Prata||||||||&#8220; header_2_line_height=&#8220;1.8em&#8220; header_4_font=&#8220;|700||on|||||&#8220; header_4_text_color=&#8220;#bea88f&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2.6px&#8220; header_4_line_height=&#8220;1.6em&#8220; header_2_font_size_tablet=&#8220;22px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4>Schwerpunkt<\/h4>\n<h2>Unterrichtsthemen<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Grundlagen des Klavierspiels erlernen&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Entwicklung der Fingerfertigkeit und Technik&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Verbesserung des musikalischen Ausdrucks&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Lernen, verschiedene Musikgenres zu spielen&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Erweiterung des musikalischen Repertoires&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_blurb title=&#8220;Verbesserung des Rhythmus und Timing&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Entwicklung des Geh\u00f6rs und Musikverst\u00e4ndnisses&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Verbesserung des Zusammenspiels mit anderen Instrumenten&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Interpretation und Improvisation von Musikst\u00fccken&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Vorbereitung auf Konzerte oder Auftritte&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x5e;||divi||400&#8243; icon_color=&#8220;#bea88f&#8220; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;20px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.18.0&#8243; header_font=&#8220;|700|||||||&#8220; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.4em&#8220; custom_margin=&#8220;||5px||false|false&#8220; animation=&#8220;off&#8220; icon_font_size=&#8220;20px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;1px||0px|||&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||50px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;https:\/\/academia-musica.at\/musikschule\/kontakt\/&#8220; button_text=&#8220;Jetzt anmelden&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.18.0&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;18px&#8220; button_text_color=&#8220;#000000&#8243; button_bg_color=&#8220;RGBA(255,255,255,0)&#8220; button_border_color=&#8220;#bea88f&#8220; button_letter_spacing=&#8220;2px&#8220; button_font=&#8220;Prata|500|||||||&#8220; custom_padding=&#8220;15px|35px|15px|35px|true|true&#8220; animation_style=&#8220;flip&#8220; box_shadow_style=&#8220;preset3&#8243; box_shadow_vertical=&#8220;14px&#8220; box_shadow_blur=&#8220;10px&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#d4af37&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_text_color__hover_enabled=&#8220;on|hover&#8220; button_text_color__hover=&#8220;#FFFFFF&#8220; custom_margin__hover_enabled=&#8220;off|desktop&#8220; custom_padding__hover_enabled=&#8220;on|hover&#8220; custom_padding__hover=&#8220;|50px||50px|true|true&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Klavier Sie interessieren sich f\u00fcr dieses Instrument?Klavier Ein Instrument f\u00fcr die Seele Das Klavier ist ein Tasteninstrument, das aus einer Reihe von horizontal angeordneten Tasten besteht, die mit H\u00e4mmerchen verbunden sind, welche wiederum die Saiten im Inneren des Klaviers anschlagen. Jede Taste entspricht einer bestimmten Tonh\u00f6he und Dynamik, die der Spieler durch die St\u00e4rke des [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1872,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1904"}],"collection":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/comments?post=1904"}],"version-history":[{"count":4,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1904\/revisions"}],"predecessor-version":[{"id":2578,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1904\/revisions\/2578"}],"up":[{"embeddable":true,"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/pages\/1872"}],"wp:attachment":[{"href":"https:\/\/academia-musica.at\/musikschule\/wp-json\/wp\/v2\/media?parent=1904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}